{"id":98,"date":"2024-03-11T02:50:41","date_gmt":"2024-03-11T02:50:41","guid":{"rendered":"https:\/\/greener-bkk.local\/?page_id=98"},"modified":"2024-05-20T15:56:09","modified_gmt":"2024-05-20T08:56:09","slug":"pm-2-5-dust-protection-and-health-tips","status":"publish","type":"page","link":"https:\/\/greener.1dd.co\/en\/pm2-5\/pm-2-5-dust-protection-and-health-tips\/","title":{"rendered":"Self-care guide from PM 2.5 dust"},"content":{"rendered":"<p>\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1d\u0e38\u0e48\u0e19 PM2.5 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e01\u0e25\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e01\u0e23\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e23\u0e32\u0e08\u0e23\u0e04\u0e31\u0e1a\u0e04\u0e31\u0e48\u0e07 \u0e40\u0e23\u0e32\u0e08\u0e36\u0e07\u0e04\u0e27\u0e23\u0e2b\u0e31\u0e19\u0e21\u0e32\u0e14\u0e39\u0e41\u0e25\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32 \u0e21\u0e32\u0e14\u0e39\u0e27\u0e34\u0e18\u0e35\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22! \u201c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u201d \u0e27\u0e31\u0e14\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23?  How to \u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e1d\u0e38\u0e48\u0e19 PM2.5 \u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e08\u0e32\u0e01 PM2.5 \u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e1d\u0e38\u0e48\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1d\u0e38\u0e48\u0e19 PM2.5 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e01\u0e25\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e01\u0e23\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e23\u0e32\u0e08\u0e23\u0e04\u0e31\u0e1a\u0e04\u0e31\u0e48\u0e07 \u0e40\u0e23\u0e32\u0e08\u0e36\u0e07\u0e04\u0e27\u0e23\u0e2b\u0e31\u0e19\u0e21\u0e32\u0e14\u0e39\u0e41\u0e25\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32 \u0e21\u0e32\u0e14\u0e39\u0e27\u0e34\u0e18\u0e35\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22! \u201c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u201d \u0e27\u0e31\u0e14\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23? How to \u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e1d\u0e38\u0e48\u0e19 PM2.5 \u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e08\u0e32\u0e01 PM2.5 \u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e1d\u0e38\u0e48\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22<\/p>","protected":false},"author":1,"featured_media":0,"parent":74,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-98","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u2028\u0e08\u0e32\u0e01\u0e1d\u0e38\u0e48\u0e19 PM 2.5 - Greener Bangkok<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greener.1dd.co\/en\/pm2-5\/pm-2-5-dust-protection-and-health-tips\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u2028\u0e08\u0e32\u0e01\u0e1d\u0e38\u0e48\u0e19 PM 2.5 - Greener Bangkok\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1d\u0e38\u0e48\u0e19 PM2.5 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e01\u0e25\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e01\u0e23\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e23\u0e32\u0e08\u0e23\u0e04\u0e31\u0e1a\u0e04\u0e31\u0e48\u0e07 \u0e40\u0e23\u0e32\u0e08\u0e36\u0e07\u0e04\u0e27\u0e23\u0e2b\u0e31\u0e19\u0e21\u0e32\u0e14\u0e39\u0e41\u0e25\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32 \u0e21\u0e32\u0e14\u0e39\u0e27\u0e34\u0e18\u0e35\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22! \u201c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u201d \u0e27\u0e31\u0e14\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23? How to \u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e1d\u0e38\u0e48\u0e19 PM2.5 \u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e08\u0e32\u0e01 PM2.5 \u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e1d\u0e38\u0e48\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greener.1dd.co\/en\/pm2-5\/pm-2-5-dust-protection-and-health-tips\/\" \/>\n<meta property=\"og:site_name\" content=\"Greener Bangkok\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-20T08:56:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greener.1dd.co\/wp-content\/uploads\/2024\/05\/share.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/pm2-5\\\/pm-2-5-dust-protection-and-health-tips\\\/\",\"url\":\"https:\\\/\\\/greener.1dd.co\\\/pm2-5\\\/pm-2-5-dust-protection-and-health-tips\\\/\",\"name\":\"\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\\u2028\u0e08\u0e32\u0e01\u0e1d\u0e38\u0e48\u0e19 PM 2.5 - Greener Bangkok\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/#website\"},\"datePublished\":\"2024-03-11T02:50:41+00:00\",\"dateModified\":\"2024-05-20T08:56:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/pm2-5\\\/pm-2-5-dust-protection-and-health-tips\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greener.1dd.co\\\/pm2-5\\\/pm-2-5-dust-protection-and-health-tips\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/pm2-5\\\/pm-2-5-dust-protection-and-health-tips\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/greener.1dd.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1d\u0e38\u0e48\u0e19 PM2.5\",\"item\":\"https:\\\/\\\/greener.1dd.co\\\/pm2-5\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\\u2028\u0e08\u0e32\u0e01\u0e1d\u0e38\u0e48\u0e19 PM 2.5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/#website\",\"url\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/\",\"name\":\"Greener Bangkok\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Self-care guide from PM 2.5 dust - Greener Bangkok","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greener.1dd.co\/en\/pm2-5\/pm-2-5-dust-protection-and-health-tips\/","og_locale":"en_US","og_type":"article","og_title":"\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u2028\u0e08\u0e32\u0e01\u0e1d\u0e38\u0e48\u0e19 PM 2.5 - Greener Bangkok","og_description":"\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1d\u0e38\u0e48\u0e19 PM2.5 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e01\u0e25\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e01\u0e23\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e23\u0e32\u0e08\u0e23\u0e04\u0e31\u0e1a\u0e04\u0e31\u0e48\u0e07 \u0e40\u0e23\u0e32\u0e08\u0e36\u0e07\u0e04\u0e27\u0e23\u0e2b\u0e31\u0e19\u0e21\u0e32\u0e14\u0e39\u0e41\u0e25\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32 \u0e21\u0e32\u0e14\u0e39\u0e27\u0e34\u0e18\u0e35\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22! \u201c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u201d \u0e27\u0e31\u0e14\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23? How to \u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e1d\u0e38\u0e48\u0e19 PM2.5 \u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e08\u0e32\u0e01 PM2.5 \u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e1d\u0e38\u0e48\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22","og_url":"https:\/\/greener.1dd.co\/en\/pm2-5\/pm-2-5-dust-protection-and-health-tips\/","og_site_name":"Greener Bangkok","article_modified_time":"2024-05-20T08:56:09+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/greener.1dd.co\/wp-content\/uploads\/2024\/05\/share.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/greener.1dd.co\/pm2-5\/pm-2-5-dust-protection-and-health-tips\/","url":"https:\/\/greener.1dd.co\/pm2-5\/pm-2-5-dust-protection-and-health-tips\/","name":"Self-care guide from PM 2.5 dust - Greener Bangkok","isPartOf":{"@id":"https:\/\/greenerbkk.wpengine.com\/#website"},"datePublished":"2024-03-11T02:50:41+00:00","dateModified":"2024-05-20T08:56:09+00:00","breadcrumb":{"@id":"https:\/\/greener.1dd.co\/pm2-5\/pm-2-5-dust-protection-and-health-tips\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greener.1dd.co\/pm2-5\/pm-2-5-dust-protection-and-health-tips\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/greener.1dd.co\/pm2-5\/pm-2-5-dust-protection-and-health-tips\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/greener.1dd.co\/"},{"@type":"ListItem","position":2,"name":"\u0e1d\u0e38\u0e48\u0e19 PM2.5","item":"https:\/\/greener.1dd.co\/pm2-5\/"},{"@type":"ListItem","position":3,"name":"\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u2028\u0e08\u0e32\u0e01\u0e1d\u0e38\u0e48\u0e19 PM 2.5"}]},{"@type":"WebSite","@id":"https:\/\/greenerbkk.wpengine.com\/#website","url":"https:\/\/greenerbkk.wpengine.com\/","name":"Greener Bangkok","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greenerbkk.wpengine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/pages\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/comments?post=98"}],"version-history":[{"count":0,"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/pages\/98\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/pages\/74"}],"wp:attachment":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/media?parent=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}