{"id":22845,"date":"2026-02-25T22:27:15","date_gmt":"2026-02-25T15:27:15","guid":{"rendered":"https:\/\/greener.1dd.co\/?post_type=event&#038;p=22845"},"modified":"2026-02-25T22:27:18","modified_gmt":"2026-02-25T15:27:18","slug":"in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87","status":"publish","type":"event","link":"https:\/\/greener.1dd.co\/en\/event\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\/","title":{"rendered":"In Between (\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07)"},"content":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 &#8211; 7 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569<\/p>\n\n\n\n<p>\u0e13 \u0e23\u0e34\u0e0a\u0e32\u0e23\u0e4c\u0e14 \u0e42\u0e04\u0e2b\u0e4c \u0e44\u0e1f\u0e19\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f<\/p>\n\n\n\n<p>\u0e23\u0e34\u0e0a\u0e32\u0e23\u0e4c\u0e14 \u0e42\u0e04\u0e2b\u0e4c \u0e44\u0e1f\u0e19\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d In Between \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\u0e42\u0e14\u0e22\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e44\u0e17\u0e22 \u0e01\u0e19\u0e01\u0e1e\u0e25 \u0e2a\u0e21\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e16\u0e36\u0e07 7 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e1b\u0e34\u0e14\u0e17\u0e33\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 14\u201326 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e08\u0e34\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e38\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e04\u0e23\u0e48\u0e04\u0e23\u0e27\u0e0d\u0e16\u0e36\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e48\u0e07\u0e2a\u0e07\u0e1a \u0e41\u0e25\u0e30\u0e20\u0e32\u0e27\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19 \u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e49\u0e32\u0e27\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e0b\u0e36\u0e48\u0e07\u0e14\u0e33\u0e23\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e17\u0e23\u0e07\u0e08\u0e33 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a<\/p>\n\n\n\n<p>\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e19\u0e01\u0e1e\u0e25\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e23\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e2d\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e2b\u0e22\u0e38\u0e14\u0e19\u0e34\u0e48\u0e07 \u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e23\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e22\u0e1a \u0e2b\u0e32\u0e01\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32 \u0e25\u0e21 \u0e1d\u0e19 \u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e2a\u0e07\u0e41\u0e25\u0e30\u0e40\u0e07\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48 \u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e1d\u0e49\u0e32\u0e21\u0e2d\u0e07\u0e14\u0e27\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e25\u0e31\u0e1a\u0e15\u0e32 \u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e14\u0e27\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e1f\u0e49\u0e32\u0e40\u0e1b\u0e34\u0e14 \u0e01\u0e32\u0e23\u0e17\u0e2d\u0e14\u0e2a\u0e32\u0e22\u0e15\u0e32\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e41\u0e19\u0e27\u0e20\u0e39\u0e40\u0e02\u0e32 \u0e40\u0e21\u0e06\u0e17\u0e35\u0e48 \u0e25\u0e48\u0e2d\u0e07\u0e25\u0e2d\u0e22\u0e1a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e1f\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e25\u0e49\u0e27\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e14\u0e4d\u0e32\u0e23\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07 \u0e0a\u0e35\u0e27\u0e34\u0e15<\/p>\n\n\n\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e0a\u0e38\u0e14 In Between (\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07) \u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e19\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28 \u0e2a\u0e20\u0e32\u0e27\u0e30\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e22\u0e15\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48 \u0e04\u0e25\u0e38\u0e21\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e17\u0e23\u0e07\u0e08\u0e4d\u0e32 \u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e13\u0e30\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e40\u0e25\u0e37\u0e2d\u0e19\u0e2b\u0e32\u0e22 \u201c\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u201d \u0e04\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e23\u0e34\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e01\u0e31\u0e1a\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e17\u0e35\u0e48\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e25\u0e32\u0e22\u0e15\u0e31\u0e27<\/p>\n\n\n\n<p>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e20\u0e32\u0e1e\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e15\u0e32\u0e22\u0e15\u0e31\u0e27 \u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e07\u0e40\u0e2d\u0e34\u0e0d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e08\u0e34\u0e15\u0e2a\u0e4d\u0e32\u0e19\u0e36\u0e01 \u0e44\u0e14\u0e49\u0e17\u0e4d\u0e32\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e20\u0e32\u0e1e\u0e08\u0e36\u0e07\u0e04\u0e48\u0e2d\u0e22 \u0e46 \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e17\u0e4d\u0e32\u0e07\u0e32\u0e19 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e16\u0e39\u0e01\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e4d\u0e32\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e04\u0e27\u0e32\u0e21\u0e04\u0e25\u0e38\u0e21\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30 \u0e41\u0e25\u0e30\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e43\u0e19 \u0e1c\u0e25\u0e07\u0e32\u0e19 \u0e17\u0e4d\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e41\u0e1b\u0e23\u0e1b\u0e23\u0e27\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e27\u0e32\u0e07<\/p>\n\n\n\n<p>\u0e01\u0e19\u0e01\u0e1e\u0e25\u0e40\u0e01\u0e34\u0e14\u0e41\u0e25\u0e30\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u0e04\u0e27\u0e32\u0e21\u0e1c\u0e39\u0e01\u0e1e\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e22\u0e31\u0e07\u0e04\u0e07\u0e2b\u0e25\u0e48\u0e2d\u0e2b\u0e25\u0e2d\u0e21\u0e20\u0e32\u0e29\u0e32\u0e17\u0e32\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e04\u0e23\u0e48\u0e04\u0e23\u0e27\u0e0d\u0e15\u0e48\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e41\u0e23\u0e07\u0e01\u0e48\u0e2d\u0e23\u0e39\u0e1b\u0e2a\u0e33\u0e04\u0e31\u0e0d\u2014\u0e41\u0e23\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e08\u0e34\u0e15\u0e2a\u0e33\u0e19\u0e36\u0e01 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e1c\u0e48\u0e32\u0e19 In Between \u0e01\u0e19\u0e01\u0e1e\u0e25\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e43\u0e2b\u0e49\u0e0a\u0e30\u0e25\u0e2d\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30 \u0e25\u0e07\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e41\u0e25\u0e30\u0e1e\u0e33\u0e19\u0e31\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e22\u0e32\u0e01\u0e08\u0e30\u0e19\u0e34\u0e22\u0e32\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e36\u0e01\u0e0b\u0e36\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e02\u0e13\u0e30<\/p>","protected":false},"featured_media":22846,"parent":0,"template":"","event-categorie":[45],"class_list":["post-22845","event","type-event","status-publish","has-post-thumbnail","hentry","event-categorie-art-culture"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In Between (\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07) - Greener Bangkok<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greener.1dd.co\/en\/event\/in-between-\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In Between (\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07) - Greener Bangkok\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 &#8211; 7 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569 \u0e13 \u0e23\u0e34\u0e0a\u0e32\u0e23\u0e4c\u0e14 \u0e42\u0e04\u0e2b\u0e4c \u0e44\u0e1f\u0e19\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e23\u0e34\u0e0a\u0e32\u0e23\u0e4c\u0e14 \u0e42\u0e04\u0e2b\u0e4c \u0e44\u0e1f\u0e19\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d In Between \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\u0e42\u0e14\u0e22\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e44\u0e17\u0e22 \u0e01\u0e19\u0e01\u0e1e\u0e25 \u0e2a\u0e21\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e16\u0e36\u0e07 7 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e1b\u0e34\u0e14\u0e17\u0e33\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 14\u201326 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e08\u0e34\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e38\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e04\u0e23\u0e48\u0e04\u0e23\u0e27\u0e0d\u0e16\u0e36\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e48\u0e07\u0e2a\u0e07\u0e1a \u0e41\u0e25\u0e30\u0e20\u0e32\u0e27\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19 \u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e49\u0e32\u0e27\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e0b\u0e36\u0e48\u0e07\u0e14\u0e33\u0e23\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e17\u0e23\u0e07\u0e08\u0e33 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e19\u0e01\u0e1e\u0e25\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e23\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e2d\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e2b\u0e22\u0e38\u0e14\u0e19\u0e34\u0e48\u0e07 \u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e23\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e22\u0e1a \u0e2b\u0e32\u0e01\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32 \u0e25\u0e21 \u0e1d\u0e19 \u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e2a\u0e07\u0e41\u0e25\u0e30\u0e40\u0e07\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48 \u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e1d\u0e49\u0e32\u0e21\u0e2d\u0e07\u0e14\u0e27\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e25\u0e31\u0e1a\u0e15\u0e32 \u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e14\u0e27\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e1f\u0e49\u0e32\u0e40\u0e1b\u0e34\u0e14 \u0e01\u0e32\u0e23\u0e17\u0e2d\u0e14\u0e2a\u0e32\u0e22\u0e15\u0e32\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e41\u0e19\u0e27\u0e20\u0e39\u0e40\u0e02\u0e32 \u0e40\u0e21\u0e06\u0e17\u0e35\u0e48 \u0e25\u0e48\u0e2d\u0e07\u0e25\u0e2d\u0e22\u0e1a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e1f\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greener.1dd.co\/en\/event\/in-between-\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\/\" \/>\n<meta property=\"og:site_name\" content=\"Greener Bangkok\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T15:27:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greener.1dd.co\/wp-content\/uploads\/2024\/05\/share.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\\\/\",\"url\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\\\/\",\"name\":\"In Between (\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07) - Greener Bangkok\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greener.1dd.co\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/in-between-kanokpon-somchua.avif\",\"datePublished\":\"2026-02-25T15:27:15+00:00\",\"dateModified\":\"2026-02-25T15:27:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greener.1dd.co\\\/event\\\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greener.1dd.co\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/in-between-kanokpon-somchua.avif\",\"contentUrl\":\"https:\\\/\\\/greener.1dd.co\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/in-between-kanokpon-somchua.avif\",\"width\":2048,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/greener.1dd.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1b\u0e0f\u0e34\u0e17\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\",\"item\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"In Between (\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/#website\",\"url\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/\",\"name\":\"Greener Bangkok\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In Between (\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07) - Greener Bangkok","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greener.1dd.co\/en\/event\/in-between-\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\/","og_locale":"en_US","og_type":"article","og_title":"In Between (\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07) - Greener Bangkok","og_description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 &#8211; 7 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569 \u0e13 \u0e23\u0e34\u0e0a\u0e32\u0e23\u0e4c\u0e14 \u0e42\u0e04\u0e2b\u0e4c \u0e44\u0e1f\u0e19\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e23\u0e34\u0e0a\u0e32\u0e23\u0e4c\u0e14 \u0e42\u0e04\u0e2b\u0e4c \u0e44\u0e1f\u0e19\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d In Between \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\u0e42\u0e14\u0e22\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e44\u0e17\u0e22 \u0e01\u0e19\u0e01\u0e1e\u0e25 \u0e2a\u0e21\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e16\u0e36\u0e07 7 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e1b\u0e34\u0e14\u0e17\u0e33\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 14\u201326 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e08\u0e34\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e38\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e04\u0e23\u0e48\u0e04\u0e23\u0e27\u0e0d\u0e16\u0e36\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e48\u0e07\u0e2a\u0e07\u0e1a \u0e41\u0e25\u0e30\u0e20\u0e32\u0e27\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19 \u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e49\u0e32\u0e27\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e0b\u0e36\u0e48\u0e07\u0e14\u0e33\u0e23\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e17\u0e23\u0e07\u0e08\u0e33 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e19\u0e01\u0e1e\u0e25\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e23\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e2d\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e2b\u0e22\u0e38\u0e14\u0e19\u0e34\u0e48\u0e07 \u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e23\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e22\u0e1a \u0e2b\u0e32\u0e01\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32 \u0e25\u0e21 \u0e1d\u0e19 \u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e2a\u0e07\u0e41\u0e25\u0e30\u0e40\u0e07\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48 \u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e1d\u0e49\u0e32\u0e21\u0e2d\u0e07\u0e14\u0e27\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e25\u0e31\u0e1a\u0e15\u0e32 \u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e14\u0e27\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e1f\u0e49\u0e32\u0e40\u0e1b\u0e34\u0e14 \u0e01\u0e32\u0e23\u0e17\u0e2d\u0e14\u0e2a\u0e32\u0e22\u0e15\u0e32\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e41\u0e19\u0e27\u0e20\u0e39\u0e40\u0e02\u0e32 \u0e40\u0e21\u0e06\u0e17\u0e35\u0e48 \u0e25\u0e48\u0e2d\u0e07\u0e25\u0e2d\u0e22\u0e1a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e1f\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 [&hellip;]","og_url":"https:\/\/greener.1dd.co\/en\/event\/in-between-\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\/","og_site_name":"Greener Bangkok","article_modified_time":"2026-02-25T15:27:18+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/greener.1dd.co\/wp-content\/uploads\/2024\/05\/share.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/greener.1dd.co\/event\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\/","url":"https:\/\/greener.1dd.co\/event\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\/","name":"In Between (\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07) - Greener Bangkok","isPartOf":{"@id":"https:\/\/greenerbkk.wpengine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greener.1dd.co\/event\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\/#primaryimage"},"image":{"@id":"https:\/\/greener.1dd.co\/event\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\/#primaryimage"},"thumbnailUrl":"https:\/\/greener.1dd.co\/wp-content\/uploads\/2026\/02\/in-between-kanokpon-somchua.avif","datePublished":"2026-02-25T15:27:15+00:00","dateModified":"2026-02-25T15:27:18+00:00","breadcrumb":{"@id":"https:\/\/greener.1dd.co\/event\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greener.1dd.co\/event\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greener.1dd.co\/event\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\/#primaryimage","url":"https:\/\/greener.1dd.co\/wp-content\/uploads\/2026\/02\/in-between-kanokpon-somchua.avif","contentUrl":"https:\/\/greener.1dd.co\/wp-content\/uploads\/2026\/02\/in-between-kanokpon-somchua.avif","width":2048,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/greener.1dd.co\/event\/in-between-%e0%b9%83%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/greener.1dd.co\/"},{"@type":"ListItem","position":2,"name":"\u0e1b\u0e0f\u0e34\u0e17\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21","item":"https:\/\/greener.1dd.co\/event\/"},{"@type":"ListItem","position":3,"name":"In Between (\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07)"}]},{"@type":"WebSite","@id":"https:\/\/greenerbkk.wpengine.com\/#website","url":"https:\/\/greenerbkk.wpengine.com\/","name":"Greener Bangkok","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greenerbkk.wpengine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/event\/22845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/media\/22846"}],"wp:attachment":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/media?parent=22845"}],"wp:term":[{"taxonomy":"event-categorie","embeddable":true,"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/event-categorie?post=22845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}