{"id":22836,"date":"2026-02-25T22:07:02","date_gmt":"2026-02-25T15:07:02","guid":{"rendered":"https:\/\/greener.1dd.co\/?post_type=event&#038;p=22836"},"modified":"2026-02-25T22:07:05","modified_gmt":"2026-02-25T15:07:05","slug":"bac-passport-winter-edition-2026","status":"publish","type":"event","link":"https:\/\/greener.1dd.co\/en\/event\/bac-passport-winter-edition-2026\/","title":{"rendered":"BAC Passport Winter Edition 2026"},"content":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c &#8211; 31 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569<\/p>\n\n\n\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e37\u0e19\u0e1c\u0e49\u0e32\u0e43\u0e1a\u0e43\u0e2b\u0e0d\u0e48 \u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e25\u0e48\u0e21\u0e40\u0e14\u0e35\u0e22\u0e27\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13 &#8216;\u0e2b\u0e25\u0e07(\u0e43\u0e2b\u0e25)&#8217; \u0e44\u0e1b\u0e43\u0e19\u0e42\u0e25\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30 27 \u0e2b\u0e21\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e31\u0e48\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07<\/p>\n\n\n\n<p>\u0e01\u0e17\u0e21. \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a Bangkok Art City (BAC) \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e09\u0e1a\u0e31\u0e1a\u0e43\u0e2b\u0e21\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e2f \u0e28\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e2b\u0e27\u0e31\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e38\u0e0d \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2d\u0e38\u0e14\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e32\u0e01\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07 10 \u0e41\u0e2b\u0e48\u0e07 \u0e2a\u0e39\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e16\u0e36\u0e07 27 \u0e2b\u0e21\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07<\/p>\n\n\n\n<p><strong>\u0e44\u0e2e\u0e44\u0e25\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14\u0e43\u0e19\u0e0b\u0e35\u0e0b\u0e31\u0e19\u0e19\u0e35\u0e49<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>4 Art Routes \u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e2a\u0e2d\u0e07\u0e1d\u0e31\u0e48\u0e07\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e22\u0e48\u0e32\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e01\u0e48\u0e32 (Heritage), \u0e22\u0e48\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 (Urban), \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d (Upstream) \u0e41\u0e25\u0e30\u0e25\u0e48\u0e2d\u0e07\u0e43\u0e15\u0e49 (Downstream)<\/li>\n\n\n\n<li>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Original Remake \u0e2a\u0e27\u0e21\u0e1a\u0e17\u0e19\u0e31\u0e01\u0e2a\u0e37\u0e1a\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e2d\u0e2d\u0e01\u0e15\u0e32\u0e21\u0e2b\u0e32 &#8220;\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e48\u0e2d\u0e07\u0e2b\u0e19&#8221; \u0e08\u0e32\u0e01\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 4 \u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07 (\u0e28.\u0e17\u0e34\u0e19\u0e01\u0e23, Hongtae, \u0e1b\u0e0f\u0e34\u0e20\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e31\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c)<\/li>\n\n\n\n<li>\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15: \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e31\u0e49\u0e07\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e21\u0e38\u0e14\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e04\u0e38\u0e13\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35, \u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c, \u0e23\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e46 \u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f<\/li>\n\n\n\n<li>\u0e23\u0e31\u0e1a\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 7 \u0e08\u0e38\u0e14\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<br>\u0e2b\u0e2d\u0e28\u0e34\u0e25\u0e1b\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e21\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19, River City Bangkok, \u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e38\u0e2c\u0e32\u0e2f, \u0e2b\u0e2d\u0e2a\u0e21\u0e38\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07, \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e34\u0e27\u0e31\u0e12\u0e19\u0e32, \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e31\u0e28\u0e27\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e17\u0e2d\u0e07 \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e2a\u0e40\u0e1b\u0e0b<\/li>\n<\/ul>\n\n\n\n<p>\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e08 <a href=\"https:\/\/www.facebook.com\/bangkokartcity\">Bangkok Art City<\/a><\/p>","protected":false},"featured_media":22838,"parent":0,"template":"","event-categorie":[43,45,46],"class_list":["post-22836","event","type-event","status-publish","has-post-thumbnail","hentry","event-categorie-entertainment","event-categorie-art-culture","event-categorie-free"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BAC Passport Winter Edition 2026 - Greener Bangkok<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greener.1dd.co\/en\/event\/bac-passport-winter-edition-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAC Passport Winter Edition 2026 - Greener Bangkok\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c &#8211; 31 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e37\u0e19\u0e1c\u0e49\u0e32\u0e43\u0e1a\u0e43\u0e2b\u0e0d\u0e48 \u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e25\u0e48\u0e21\u0e40\u0e14\u0e35\u0e22\u0e27\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13 &#8216;\u0e2b\u0e25\u0e07(\u0e43\u0e2b\u0e25)&#8217; \u0e44\u0e1b\u0e43\u0e19\u0e42\u0e25\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30 27 \u0e2b\u0e21\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e31\u0e48\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e01\u0e17\u0e21. \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a Bangkok Art City (BAC) \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e09\u0e1a\u0e31\u0e1a\u0e43\u0e2b\u0e21\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e2f \u0e28\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e2b\u0e27\u0e31\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e38\u0e0d \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2d\u0e38\u0e14\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e32\u0e01\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07 10 \u0e41\u0e2b\u0e48\u0e07 \u0e2a\u0e39\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e16\u0e36\u0e07 27 \u0e2b\u0e21\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07 \u0e44\u0e2e\u0e44\u0e25\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14\u0e43\u0e19\u0e0b\u0e35\u0e0b\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e08 Bangkok Art City\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greener.1dd.co\/en\/event\/bac-passport-winter-edition-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Greener Bangkok\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T15:07:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greener.1dd.co\/wp-content\/uploads\/2026\/02\/639694217_1426487369488947_1930895852945084184_n.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/bac-passport-winter-edition-2026\\\/\",\"url\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/bac-passport-winter-edition-2026\\\/\",\"name\":\"BAC Passport Winter Edition 2026 - Greener Bangkok\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/bac-passport-winter-edition-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/bac-passport-winter-edition-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greener.1dd.co\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/639694217_1426487369488947_1930895852945084184_n.webp\",\"datePublished\":\"2026-02-25T15:07:02+00:00\",\"dateModified\":\"2026-02-25T15:07:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/bac-passport-winter-edition-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greener.1dd.co\\\/event\\\/bac-passport-winter-edition-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/bac-passport-winter-edition-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greener.1dd.co\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/639694217_1426487369488947_1930895852945084184_n.webp\",\"contentUrl\":\"https:\\\/\\\/greener.1dd.co\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/639694217_1426487369488947_1930895852945084184_n.webp\",\"width\":2048,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/bac-passport-winter-edition-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/greener.1dd.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1b\u0e0f\u0e34\u0e17\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\",\"item\":\"https:\\\/\\\/greener.1dd.co\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BAC Passport Winter Edition 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/#website\",\"url\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/\",\"name\":\"Greener Bangkok\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BAC Passport Winter Edition 2026 - Greener Bangkok","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greener.1dd.co\/en\/event\/bac-passport-winter-edition-2026\/","og_locale":"en_US","og_type":"article","og_title":"BAC Passport Winter Edition 2026 - Greener Bangkok","og_description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c &#8211; 31 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e37\u0e19\u0e1c\u0e49\u0e32\u0e43\u0e1a\u0e43\u0e2b\u0e0d\u0e48 \u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e25\u0e48\u0e21\u0e40\u0e14\u0e35\u0e22\u0e27\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1e\u0e32\u0e04\u0e38\u0e13 &#8216;\u0e2b\u0e25\u0e07(\u0e43\u0e2b\u0e25)&#8217; \u0e44\u0e1b\u0e43\u0e19\u0e42\u0e25\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30 27 \u0e2b\u0e21\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e31\u0e48\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e01\u0e17\u0e21. \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a Bangkok Art City (BAC) \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e09\u0e1a\u0e31\u0e1a\u0e43\u0e2b\u0e21\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e2f \u0e28\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e2b\u0e27\u0e31\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e38\u0e0d \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2d\u0e38\u0e14\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e32\u0e01\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07 10 \u0e41\u0e2b\u0e48\u0e07 \u0e2a\u0e39\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e16\u0e36\u0e07 27 \u0e2b\u0e21\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07 \u0e44\u0e2e\u0e44\u0e25\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14\u0e43\u0e19\u0e0b\u0e35\u0e0b\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e08 Bangkok Art City","og_url":"https:\/\/greener.1dd.co\/en\/event\/bac-passport-winter-edition-2026\/","og_site_name":"Greener Bangkok","article_modified_time":"2026-02-25T15:07:05+00:00","og_image":[{"width":2048,"height":2048,"url":"https:\/\/greener.1dd.co\/wp-content\/uploads\/2026\/02\/639694217_1426487369488947_1930895852945084184_n.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/greener.1dd.co\/event\/bac-passport-winter-edition-2026\/","url":"https:\/\/greener.1dd.co\/event\/bac-passport-winter-edition-2026\/","name":"BAC Passport Winter Edition 2026 - Greener Bangkok","isPartOf":{"@id":"https:\/\/greenerbkk.wpengine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greener.1dd.co\/event\/bac-passport-winter-edition-2026\/#primaryimage"},"image":{"@id":"https:\/\/greener.1dd.co\/event\/bac-passport-winter-edition-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/greener.1dd.co\/wp-content\/uploads\/2026\/02\/639694217_1426487369488947_1930895852945084184_n.webp","datePublished":"2026-02-25T15:07:02+00:00","dateModified":"2026-02-25T15:07:05+00:00","breadcrumb":{"@id":"https:\/\/greener.1dd.co\/event\/bac-passport-winter-edition-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greener.1dd.co\/event\/bac-passport-winter-edition-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greener.1dd.co\/event\/bac-passport-winter-edition-2026\/#primaryimage","url":"https:\/\/greener.1dd.co\/wp-content\/uploads\/2026\/02\/639694217_1426487369488947_1930895852945084184_n.webp","contentUrl":"https:\/\/greener.1dd.co\/wp-content\/uploads\/2026\/02\/639694217_1426487369488947_1930895852945084184_n.webp","width":2048,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/greener.1dd.co\/event\/bac-passport-winter-edition-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/greener.1dd.co\/"},{"@type":"ListItem","position":2,"name":"\u0e1b\u0e0f\u0e34\u0e17\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21","item":"https:\/\/greener.1dd.co\/event\/"},{"@type":"ListItem","position":3,"name":"BAC Passport Winter Edition 2026"}]},{"@type":"WebSite","@id":"https:\/\/greenerbkk.wpengine.com\/#website","url":"https:\/\/greenerbkk.wpengine.com\/","name":"Greener Bangkok","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greenerbkk.wpengine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/event\/22836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/media\/22838"}],"wp:attachment":[{"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/media?parent=22836"}],"wp:term":[{"taxonomy":"event-categorie","embeddable":true,"href":"https:\/\/greener.1dd.co\/en\/wp-json\/wp\/v2\/event-categorie?post=22836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}